{"id":2509,"date":"2026-08-20T08:44:24","date_gmt":"2026-08-20T08:44:24","guid":{"rendered":"https:\/\/cantorlaw.biz\/utilisation-de-societes-relais-dans-la-planification-fiscale\/"},"modified":"2026-08-31T13:59:55","modified_gmt":"2026-08-31T13:59:55","slug":"utilisation-de-societes-relais-dans-la-planification-fiscale","status":"publish","type":"post","link":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/","title":{"rendered":"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&rsquo;arr\u00eat <strong>CA 59924-03-22 Q Cyber Technologies Ltd c. Inspecteur des imp\u00f4ts de Kfar Saba<\/strong> (rendu par l&rsquo;honorable juge Avi Gorman au tribunal de district du centre-Lod) constitue l&rsquo;une des pierres angulaires majeures de ces derni\u00e8res ann\u00e9es concernant la lutte fiscale contre les op\u00e9rations de financement et d&rsquo;acquisitions par emprunt au sein de groupes de soci\u00e9t\u00e9s internationaux.<\/p>\n\n<p class=\"wp-block-paragraph\">Voici une analyse approfondie et d\u00e9taill\u00e9e de l&rsquo;arr\u00eat, des conclusions op\u00e9rationnelles et des distinctions entre le permis et l&rsquo;interdit qui en d\u00e9coulent :<\/p>\n\n<h1 class=\"wp-block-heading\">D\u00e9cision du tribunal et analyse du cas<\/h1>\n\n<p class=\"wp-block-paragraph\">Le tribunal de district a <strong>rejet\u00e9 l&rsquo;appel<\/strong> de Q Cyber Technologies Ltd (ci-apr\u00e8s : \u00ab l&rsquo;appelante \u00bb) et a enti\u00e8rement retenu la position de l&rsquo;inspecteur des imp\u00f4ts.<\/p>\n\n<p class=\"wp-block-paragraph\">Le tribunal a \u00e9tabli que la s\u00e9quence d&rsquo;op\u00e9rations effectu\u00e9es \u2013 acquisition des actions de la soci\u00e9t\u00e9 isra\u00e9lienne NSO par une soci\u00e9t\u00e9 luxembourgeoise (OSY), cr\u00e9ation de l&rsquo;appelante en tant que soci\u00e9t\u00e9 dormante isra\u00e9lienne vide de substance, transfert des actions NSO \u00e0 l&rsquo;appelante en fiducie, cr\u00e9ation de pr\u00eats d&rsquo;actionnaires d&rsquo;environ 87 millions de dollars de la soci\u00e9t\u00e9 luxembourgeoise \u00e0 l&rsquo;appelante, et leur remboursement rapide au moyen de b\u00e9n\u00e9fices et dividendes transf\u00e9r\u00e9s depuis NSO \u2013 constitue une <strong>\u00ab<\/strong><strong> op\u00e9ration artificielle<\/strong><strong> \u00bb<\/strong> selon l&rsquo;article 86 de l&rsquo;ordonnance sur l&rsquo;imp\u00f4t sur le revenu.<\/p>\n\n<p class=\"wp-block-paragraph\">En cons\u00e9quence, le tribunal a ordonn\u00e9 de <strong>ne pas tenir compte de la qualification des paiements comme remboursement de pr\u00eat (exon\u00e9r\u00e9 d&rsquo;imp\u00f4t)<\/strong>, et de les requalifier en <strong>distribution de dividendes<\/strong> soumise \u00e0 retenue \u00e0 la source lors du transfert de b\u00e9n\u00e9fices d&rsquo;Isra\u00ebl vers un r\u00e9sident \u00e9tranger.<\/p>\n\n<h1 class=\"wp-block-heading\">Montant de la r\u00e9duction d&rsquo;imp\u00f4t dans ce cas<\/h1>\n\n<p class=\"wp-block-paragraph\">Le transfert de b\u00e9n\u00e9fices d&rsquo;un montant total de plus de 86 millions de dollars d&rsquo;Isra\u00ebl vers le Luxembourg sous couvert de remboursement de pr\u00eat a permis au groupe d&rsquo;\u00e9viter le paiement de l&rsquo;imp\u00f4t sur les dividendes en deux \u00e9tapes.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Conform\u00e9ment \u00e0 la convention fiscale applicable, le taux d&rsquo;imposition applicable aux dividendes s&rsquo;\u00e9levait \u00e0 10 %.<\/li>\n\n\n\n<li>Par cons\u00e9quent, la r\u00e9duction d&rsquo;imp\u00f4t (l&rsquo;\u00e9conomie fiscale) que le groupe cherchait \u00e0 obtenir au moyen de la structure artificielle s&rsquo;\u00e9levait \u00e0 <strong>8,6<\/strong><strong> millions de dollars<\/strong>. Le tribunal a rejet\u00e9 cet avantage fiscal et a impos\u00e9 l&rsquo;appelante de l&rsquo;imp\u00f4t susmentionn\u00e9. <\/li>\n<\/ul>\n\n<h1 class=\"wp-block-heading\">Param\u00e8tres ayant conduit \u00e0 qualifier l&rsquo;op\u00e9ration d&rsquo;artificielle<\/h1>\n\n<p class=\"wp-block-paragraph\">Le tribunal a \u00e9num\u00e9r\u00e9 une s\u00e9rie de signaux d&rsquo;alerte et de param\u00e8tres factuels prouvant que l&rsquo;appelante n&rsquo;avait aucune finalit\u00e9 commerciale r\u00e9elle lors de sa cr\u00e9ation :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Soci\u00e9t\u00e9 vide de substance (coquille vide)<\/strong><strong> :<\/strong> \u00c0 la date d&rsquo;acquisition des actions NSO et durant les ann\u00e9es 2014\u20132015, l&rsquo;appelante \u00e9tait une soci\u00e9t\u00e9 dormante sans aucune activit\u00e9 commerciale, sans employ\u00e9s, sans actifs et m\u00eame sans compte bancaire actif.<\/li>\n\n\n\n<li><strong>Absence de flux de tr\u00e9sorerie r\u00e9el (contrats versus r\u00e9alit\u00e9)<\/strong><strong> :<\/strong> Les fonds ayant servi \u00e0 l&rsquo;acquisition des actions et aux remboursements de pr\u00eats d&rsquo;un montant de 86 millions de dollars ont \u00e9t\u00e9 transf\u00e9r\u00e9s directement des comptes bancaires de NSO vers les comptes de la soci\u00e9t\u00e9 m\u00e8re au Luxembourg (OSY), <strong>sans jamais transiter par le compte bancaire de l&rsquo;appelante<\/strong>.<\/li>\n\n\n\n<li><strong>Absence totale d&rsquo;autonomie de gestion<\/strong><strong> :<\/strong> Les accords et actes de transfert d&rsquo;actions ont \u00e9t\u00e9 sign\u00e9s par la m\u00eame personne au nom des deux soci\u00e9t\u00e9s (l&rsquo;appelante isra\u00e9lienne et la soci\u00e9t\u00e9 m\u00e8re \u00e9trang\u00e8re OSY).<\/li>\n\n\n\n<li><strong>Preuves contradictoires en temps r\u00e9el<\/strong><strong> :<\/strong> Une demande \u00e9crite adress\u00e9e par NSO \u00e0 l&rsquo;administration fiscale au moment de l&rsquo;acquisition indiquait express\u00e9ment que l&rsquo;acquisition serait effectu\u00e9e par une soci\u00e9t\u00e9 \u00e9trang\u00e8re, ce qui prouvait que les dirigeants de NSO eux-m\u00eames ignoraient totalement l&rsquo;existence de l&rsquo;appelante en temps r\u00e9el, et qu&rsquo;elle avait \u00e9t\u00e9 int\u00e9gr\u00e9e dans la structure de l&rsquo;op\u00e9ration a posteriori uniquement \u00e0 des fins fiscales.<\/li>\n\n\n\n<li><strong>Non-respect de la charge de la preuve<\/strong><strong> :<\/strong> L&rsquo;appelante s&rsquo;est abstenue de pr\u00e9senter des documents contemporains (tels que proc\u00e8s-verbaux, documents de travail ou plans d&rsquo;affaires de 2014) et de faire t\u00e9moigner des t\u00e9moins substantiels qui expliqueraient pourquoi l&rsquo;appelante avait \u00e9t\u00e9 cr\u00e9\u00e9e pr\u00e9cis\u00e9ment pour d\u00e9tenir les actions. Le tribunal a \u00e9tabli que cette abstention cr\u00e9ait une pr\u00e9somption de preuve \u00e0 son encontre. <\/li>\n\n\n\n<li><strong>Contradiction du plan d&rsquo;affaires all\u00e9gu\u00e9<\/strong><strong> :<\/strong> L&rsquo;appelante pr\u00e9tendait avoir \u00e9t\u00e9 cr\u00e9\u00e9e pour servir de plateforme d&rsquo;acquisition d&rsquo;autres soci\u00e9t\u00e9s isra\u00e9liennes de cybers\u00e9curit\u00e9 sous son \u00e9gide. En pratique, lorsque le groupe a acquis d&rsquo;autres soci\u00e9t\u00e9s en 2019\u20132020, elles n&rsquo;ont pas \u00e9t\u00e9 acquises sous l&rsquo;appelante mais sous une nouvelle soci\u00e9t\u00e9 isra\u00e9lienne cr\u00e9\u00e9e (Gottlieb Ltd). <\/li>\n<\/ul>\n\n<h1 class=\"wp-block-heading\">Conclusion op\u00e9rationnelle \u2013 quels types d&rsquo;op\u00e9rations faut-il \u00e9viter ?<\/h1>\n\n<p class=\"wp-block-paragraph\">La conclusion principale est qu&rsquo;il faut \u00e9viter les op\u00e9rations structur\u00e9es sous forme d&rsquo;<strong>\u00ab<\/strong><strong> implantation \u00bb d&rsquo;une entit\u00e9 interm\u00e9diaire vide<\/strong><strong> (Conduit) <\/strong><strong>d\u00e9pourvue de substance \u00e9conomique et commerciale autonome en temps r\u00e9el<\/strong>, dont le seul objectif est de canaliser des fonds et b\u00e9n\u00e9fices en franchise d&rsquo;imp\u00f4t.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Accords r\u00e9troactifs<\/strong><strong> :<\/strong> R\u00e9daction d&rsquo;accords de fiducie ou d&rsquo;accords de d\u00e9tention a posteriori afin de cr\u00e9er une apparence juridique favorable \u00e0 des fins fiscales.<\/li>\n\n\n\n<li><strong>Flux de tr\u00e9sorerie contournant<\/strong><strong> :<\/strong> Ex\u00e9cution d&rsquo;op\u00e9rations de pr\u00eat et de remboursement dans lesquelles le flux physique contourne compl\u00e8tement le compte bancaire de la soci\u00e9t\u00e9 interm\u00e9diaire et s&rsquo;effectue directement entre la soci\u00e9t\u00e9 petite-fille (la soci\u00e9t\u00e9 op\u00e9rationnelle) et la soci\u00e9t\u00e9 grand-m\u00e8re (\u00e9trang\u00e8re).<\/li>\n\n\n\n<li><strong>Op\u00e9rations fractionn\u00e9es sans logique commerciale<\/strong><strong> :<\/strong> Signature d&rsquo;une s\u00e9rie de petits accords de pr\u00eat (par exemple, plusieurs accords ne d\u00e9passant pas 5 millions de dollars chacun) sans raison apparente autre qu&rsquo;une tentative de contourner les obligations de d\u00e9claration ou d&rsquo;approbation.<\/li>\n<\/ul>\n\n<h1 class=\"wp-block-heading\">Dans quels cas la structure de l&rsquo;op\u00e9ration sera-t-elle n\u00e9anmoins reconnue ? (ce qui est permis et ce qui est interdit) <\/h1>\n\n<p class=\"wp-block-paragraph\">Pour qu&rsquo;une structure comprenant un financement par emprunt, une acquisition par emprunt (LBO) ou l&rsquo;utilisation d&rsquo;une soci\u00e9t\u00e9 holding isra\u00e9lienne soit reconnue par l&rsquo;administration fiscale et le tribunal, il faut respecter les r\u00e8gles suivantes :<\/p>\n\n<h2 class=\"wp-block-heading\">Ce qui est interdit (sera consid\u00e9r\u00e9 comme artificiel) :<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Il est interdit de s&rsquo;appuyer sur une activit\u00e9 commerciale cr\u00e9\u00e9e uniquement a posteriori (\u00ab assemblage \u00bb de contenu \u00e9conomique ult\u00e9rieur). Le tribunal a \u00e9tabli que le fait qu&rsquo;en 2016 (deux ans apr\u00e8s l&rsquo;op\u00e9ration) l&rsquo;appelante disposait d\u00e9j\u00e0 d&#8217;employ\u00e9s et d&rsquo;une activit\u00e9 marketing r\u00e9elle ne valide pas le caract\u00e8re artificiel de la structure de financement et de cr\u00e9ation telle qu&rsquo;elle existait au \u00ab moment r\u00e9el \u00bb de l&rsquo;op\u00e9ration en 2014. <\/li>\n\n\n\n<li>Il est interdit de g\u00e9rer la soci\u00e9t\u00e9 holding avec un conseil d&rsquo;administration \u00ab fantoche \u00bb passif qui ne conna\u00eet pas les affaires de la soci\u00e9t\u00e9 et n&rsquo;exerce pas de jugement ind\u00e9pendant (comme \u00e9tabli dans l&rsquo;arr\u00eat <strong>Niago<\/strong> mentionn\u00e9 dans le dossier).<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Ce qui est permis (et sera reconnu \u00e0 des fins fiscales) :<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>L&rsquo;effet de levier et le financement par emprunt sont l\u00e9gitimes<\/strong><strong> :<\/strong> En principe, l&rsquo;acquisition de soci\u00e9t\u00e9s au moyen d&#8217;emprunt et d&rsquo;effet de levier est une pratique commerciale accept\u00e9e et n&rsquo;est pas en soi r\u00e9pr\u00e9hensible.<\/li>\n\n\n\n<li><strong>Exigence de substance commerciale \u00e0 la date de cr\u00e9ation<\/strong><strong> (Day One) :<\/strong> La soci\u00e9t\u00e9 interm\u00e9diaire doit pr\u00e9senter une activit\u00e9 commerciale r\u00e9elle, des bureaux, des employ\u00e9s et des processus de prise de d\u00e9cision autonomes d\u00e8s sa cr\u00e9ation et l&rsquo;ex\u00e9cution de l&rsquo;acquisition.<\/li>\n\n\n\n<li><strong>Documentation rigoureuse en temps r\u00e9el<\/strong><strong> :<\/strong> Il est obligatoire de conserver et de documenter les correspondances, proc\u00e8s-verbaux, \u00e9valuations, pr\u00e9sentations aux investisseurs et plans d&rsquo;affaires d\u00e9montrant les raisons commerciales de la cr\u00e9ation de la structure sp\u00e9cifique (telles que la r\u00e9glementation de s\u00e9curit\u00e9 de l&rsquo;AIPAC, les restrictions juridiques ou une strat\u00e9gie commerciale av\u00e9r\u00e9e pour l&rsquo;ensemble du groupe).<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Concordance totale entre les accords et les flux :<\/strong> Les fonds de pr\u00eat et les remboursements de principal doivent transiter physiquement par les comptes bancaires des entit\u00e9s juridiques parties \u00e0 l&rsquo;op\u00e9ration, et non par des transferts directs entre soci\u00e9t\u00e9s li\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;arr\u00eat CA 59924-03-22 Q Cyber Technologies Ltd c. Inspecteur des imp\u00f4ts de Kfar Saba (rendu par l&rsquo;honorable juge Avi Gorman au tribunal de district du centre-Lod) constitue l&rsquo;une des pierres angulaires majeures de ces derni\u00e8res ann\u00e9es concernant la lutte fiscale contre les op\u00e9rations de financement et d&rsquo;acquisitions par emprunt au sein de groupes de soci\u00e9t\u00e9s internationaux. Voici une analyse approfondie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[72,73],"tags":[],"class_list":["post-2509","post","type-post","status-publish","format-standard","hentry","category-dernieres-mises-a-jour","category-impots"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale - \u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale - \u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;arr\u00eat CA 59924-03-22 Q Cyber Technologies Ltd c. Inspecteur des imp\u00f4ts de Kfar Saba (rendu par l&rsquo;honorable juge Avi Gorman au tribunal de district du centre-Lod) constitue l&rsquo;une des pierres angulaires majeures de ces derni\u00e8res ann\u00e9es concernant la lutte fiscale contre les op\u00e9rations de financement et d&rsquo;acquisitions par emprunt au sein de groupes de soci\u00e9t\u00e9s internationaux. Voici une analyse approfondie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/\" \/>\n<meta property=\"og:site_name\" content=\"\u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-20T08:44:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T13:59:55+00:00\" \/>\n<meta name=\"author\" content=\"David Cantor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Cantor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/\"},\"author\":{\"name\":\"David Cantor\",\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/#\\\/schema\\\/person\\\/0405d7346ca029191e6dc822ee997660\"},\"headline\":\"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale\",\"datePublished\":\"2026-08-20T08:44:24+00:00\",\"dateModified\":\"2026-08-31T13:59:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/\"},\"wordCount\":1446,\"commentCount\":0,\"articleSection\":[\"Derni\u00e8res mises \u00e0 jour\",\"Imp\u00f4ts\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/\",\"url\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/\",\"name\":\"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale - \u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/#website\"},\"datePublished\":\"2026-08-20T08:44:24+00:00\",\"dateModified\":\"2026-08-31T13:59:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/#\\\/schema\\\/person\\\/0405d7346ca029191e6dc822ee997660\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/utilisation-de-societes-relais-dans-la-planification-fiscale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/\",\"name\":\"\u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd\",\"description\":\"\u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/#\\\/schema\\\/person\\\/0405d7346ca029191e6dc822ee997660\",\"name\":\"David Cantor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f98000018a67314f722baefb5d6a00239ef45aed910af42ef11feb97133dd0c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f98000018a67314f722baefb5d6a00239ef45aed910af42ef11feb97133dd0c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f98000018a67314f722baefb5d6a00239ef45aed910af42ef11feb97133dd0c?s=96&d=mm&r=g\",\"caption\":\"David Cantor\"},\"url\":\"https:\\\/\\\/cantorlaw.biz\\\/fr\\\/author\\\/cantor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale - \u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/","og_locale":"fr_FR","og_type":"article","og_title":"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale - \u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd","og_description":"L&rsquo;arr\u00eat CA 59924-03-22 Q Cyber Technologies Ltd c. Inspecteur des imp\u00f4ts de Kfar Saba (rendu par l&rsquo;honorable juge Avi Gorman au tribunal de district du centre-Lod) constitue l&rsquo;une des pierres angulaires majeures de ces derni\u00e8res ann\u00e9es concernant la lutte fiscale contre les op\u00e9rations de financement et d&rsquo;acquisitions par emprunt au sein de groupes de soci\u00e9t\u00e9s internationaux. Voici une analyse approfondie [&hellip;]","og_url":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/","og_site_name":"\u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd","article_published_time":"2026-08-20T08:44:24+00:00","article_modified_time":"2026-08-31T13:59:55+00:00","author":"David Cantor","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"David Cantor","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/#article","isPartOf":{"@id":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/"},"author":{"name":"David Cantor","@id":"https:\/\/cantorlaw.biz\/fr\/#\/schema\/person\/0405d7346ca029191e6dc822ee997660"},"headline":"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale","datePublished":"2026-08-20T08:44:24+00:00","dateModified":"2026-08-31T13:59:55+00:00","mainEntityOfPage":{"@id":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/"},"wordCount":1446,"commentCount":0,"articleSection":["Derni\u00e8res mises \u00e0 jour","Imp\u00f4ts"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/","url":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/","name":"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale - \u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd","isPartOf":{"@id":"https:\/\/cantorlaw.biz\/fr\/#website"},"datePublished":"2026-08-20T08:44:24+00:00","dateModified":"2026-08-31T13:59:55+00:00","author":{"@id":"https:\/\/cantorlaw.biz\/fr\/#\/schema\/person\/0405d7346ca029191e6dc822ee997660"},"breadcrumb":{"@id":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cantorlaw.biz\/fr\/utilisation-de-societes-relais-dans-la-planification-fiscale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/cantorlaw.biz\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Utilisation de soci\u00e9t\u00e9s relais dans la planification fiscale"}]},{"@type":"WebSite","@id":"https:\/\/cantorlaw.biz\/fr\/#website","url":"https:\/\/cantorlaw.biz\/fr\/","name":"\u05e7\u05e0\u05d8\u05d5\u05e8 \u05d5\u05e9\u05d5\u05ea&#039; \u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd","description":"\u05de\u05e9\u05e8\u05d3 \u05e2\u05d5\u05e8\u05db\u05d9 \u05d3\u05d9\u05df \u05d5\u05e0\u05d5\u05d8\u05e8\u05d9\u05d5\u05e0\u05d9\u05dd","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cantorlaw.biz\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cantorlaw.biz\/fr\/#\/schema\/person\/0405d7346ca029191e6dc822ee997660","name":"David Cantor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2f98000018a67314f722baefb5d6a00239ef45aed910af42ef11feb97133dd0c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f98000018a67314f722baefb5d6a00239ef45aed910af42ef11feb97133dd0c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f98000018a67314f722baefb5d6a00239ef45aed910af42ef11feb97133dd0c?s=96&d=mm&r=g","caption":"David Cantor"},"url":"https:\/\/cantorlaw.biz\/fr\/author\/cantor\/"}]}},"_links":{"self":[{"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/posts\/2509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/comments?post=2509"}],"version-history":[{"count":0,"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/posts\/2509\/revisions"}],"wp:attachment":[{"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/media?parent=2509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/categories?post=2509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cantorlaw.biz\/fr\/wp-json\/wp\/v2\/tags?post=2509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}